{"id":12137,"date":"2024-07-15T05:56:13","date_gmt":"2024-07-15T05:56:13","guid":{"rendered":"https:\/\/naturaliapousada.com.br\/?page_id=12137"},"modified":"2025-02-18T18:08:40","modified_gmt":"2025-02-18T18:08:40","slug":"reservierungen-und-richtlinien","status":"publish","type":"page","link":"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/","title":{"rendered":"Reservierungen und Richtlinien"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12137\" class=\"elementor elementor-12137 elementor-9390\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d2005a4 e-flex e-con-boxed e-con e-parent\" data-id=\"d2005a4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2ffd30d e-con-full e-flex e-con e-child\" data-id=\"2ffd30d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23a5bf3 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"23a5bf3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">RESERVIERUNGEN<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3235147 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3235147\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><span style=\"font-weight: 400;\">Sie k\u00f6nnen Ihre Reservierung direkt im Feld unten oder \u00fcber die E-Mail <\/span><a href=\"mailto:reservations@naturaliapousada.com.br\"><span style=\"font-weight: 400;\">reservations@naturaliapousada.com.br<\/span><\/a>\u00a0<\/p><p><span style=\"font-weight: 400;\">Wir empfehlen mindestens drei volle Tage auf Ilha Grande, um die Str\u00e4nde, Wanderwege, Bootstouren und andere Aktivit\u00e4ten zu genie\u00dfen.<\/span><\/p><p><span style=\"font-weight: 400;\">Unser Tagespreis beinhaltet:\u00a0<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ceb0d4 e-grid e-con-full elementor-invisible e-con e-child\" data-id=\"4ceb0d4\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2dbe9e9 elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2dbe9e9\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/naturaliapousada.com.br\/wp-content\/uploads\/elementor\/css\/custom-widget-icon-list.min.css?ver=1778619403\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"seasona-icon- seasona-icon-wifi\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">WLAN<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Camada_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 127.8 126.2\" style=\"enable-background:new 0 0 127.8 126.2;\" xml:space=\"preserve\"><g>\t<path d=\"M116.6,34.5L95,7.9c-1.7-2.1-4.9-2.6-7.2-0.7L61.3,28.7c-2.2,1.8-2.5,5-0.7,7.2l21.6,26.6c1.8,2.2,5,2.5,7.2,0.7l26.6-21.6   C118.1,39.9,118.4,36.7,116.6,34.5z M62.7,30.5L89.3,9c1.2-1,2.9-0.8,3.9,0.4l21,25.9c-0.1,1-0.6,2-1.4,2.7L86.3,59.5   c-0.8,0.7-1.9,1-2.9,0.9l-21-25.9C61.3,33.3,61.5,31.5,62.7,30.5z\"><\/path>\t<path d=\"M7.2,58.8l31.5,12.1c2.6,1,5.6-0.3,6.5-2.9l12.1-31.5c1-2.6-0.3-5.6-2.9-6.5L22.9,17.9c-2.6-1-5.6,0.3-6.5,2.9L4.3,52.3   C3.3,54.9,4.6,57.8,7.2,58.8z M6.5,53.1l12.1-31.5c0.5-1.4,2.2-2.1,3.5-1.6c34.7,13.4,31,11.8,32,12.4c-0.2,1.2,0.6-1.4-12.3,32.2   c-0.8,2-3,3-5,2.3L6.6,55.4C6.3,54.7,6.2,53.9,6.5,53.1z\"><\/path>\t<path d=\"M58,114.1l31.2-12.8c2.6-1.1,3.8-4,2.8-6.6L79.2,63.5c-1.1-2.6-4-3.8-6.6-2.8L41.4,73.5c-2.6,1.1-3.8,4-2.8,6.6l12.8,31.2   C52.5,113.9,55.4,115.1,58,114.1z M42.3,75.6l31.2-12.8c1.4-0.6,3,0.1,3.6,1.5L88.8,93c0.3,1.8-0.6,3.6-2.3,4.3   c-32.3,13.1-31.2,13.1-32.9,13.1L40.8,79.2C40.2,77.8,40.9,76.2,42.3,75.6z\"><\/path>\t<path d=\"M85.7,37.6c1.3,1.6,3.7,1.9,5.3,0.6c1.6-1.3,1.9-3.7,0.5-5.3c-1.3-1.6-3.7-1.8-5.3-0.5C84.6,33.6,84.3,36,85.7,37.6z\"><\/path>\t<path d=\"M99.8,33.7C98.2,35,98,37.4,99.3,39c1.3,1.6,3.7,1.8,5.3,0.5c1.6-1.3,1.9-3.7,0.6-5.3C103.8,32.6,101.5,32.4,99.8,33.7z\"><\/path>\t<path d=\"M77.8,31.4c-1.3-1.6-3.7-1.8-5.3-0.5c-1.6,1.3-1.9,3.7-0.6,5.3c1.3,1.6,3.7,1.9,5.3,0.5C78.9,35.4,79.2,33.1,77.8,31.4z\"><\/path>\t<path d=\"M24,35.5c1.9,0.7,4.1-0.2,4.8-2.1c0.7-1.9-0.2-4.1-2.1-4.8c-1.9-0.7-4,0.2-4.8,2.1C21.1,32.7,22.1,34.8,24,35.5z\"><\/path>\t<path d=\"M39.7,37.6c-0.7,1.9,0.2,4,2.1,4.8c1.9,0.7,4-0.2,4.8-2.1c0.7-1.9-0.2-4.1-2.1-4.8C42.6,34.7,40.4,35.7,39.7,37.6z\"><\/path>\t<path d=\"M37.6,53.3c-1.9-0.7-4.1,0.2-4.8,2.1c-0.7,1.9,0.2,4.1,2.1,4.8c1.9,0.7,4-0.2,4.8-2.1C40.5,56.2,39.5,54,37.6,53.3z\"><\/path>\t<path d=\"M15,48.6c-0.7,1.9,0.2,4.1,2.1,4.8c1.9,0.7,4.1-0.2,4.8-2.1c0.7-1.9-0.2-4-2.1-4.8C17.9,45.7,15.7,46.7,15,48.6z\"><\/path>\t<path d=\"M71.9,78.3c1.9-0.8,2.8-2.9,2-4.8c-0.8-1.9-2.9-2.8-4.8-2c-1.9,0.8-2.8,2.9-2,4.8C67.9,78.2,70.1,79.1,71.9,78.3z\"><\/path>\t<path d=\"M76.4,89.2c-1.9,0.8-2.8,2.9-2,4.8c0.8,1.9,2.9,2.8,4.8,2c1.9-0.8,2.8-2.9,2-4.8C80.4,89.3,78.3,88.4,76.4,89.2z\"><\/path>\t<path d=\"M58.7,96.4c-1.9,0.8-2.8,2.9-2,4.8c0.8,1.9,2.9,2.8,4.8,2c1.9-0.8,2.8-2.9,2-4.8C62.8,96.5,60.6,95.6,58.7,96.4z\"><\/path>\t<path d=\"M54.3,85.6c1.9-0.8,2.8-2.9,2-4.8c-0.8-1.9-2.9-2.8-4.8-2c-1.9,0.8-2.8,2.9-2,4.8C50.2,85.5,52.4,86.4,54.3,85.6z\"><\/path>\t<path d=\"M72.8,80.3c-1.9,0.8-2.8,2.9-2,4.8c0.8,1.9,2.9,2.8,4.8,2c1.9-0.8,2.8-2.9,2-4.8C76.8,80.5,74.7,79.5,72.8,80.3z\"><\/path>\t<path d=\"M57.9,94.4c1.9-0.8,2.8-2.9,2-4.8c-0.8-1.9-2.9-2.8-4.8-2c-1.9,0.8-2.8,2.9-2,4.8C53.8,94.3,56,95.2,57.9,94.4z\"><\/path>\t<path d=\"M77.9,24.2l7.8-6.1c0.5-0.4,0.6-1.1,0.2-1.6s-1.1-0.6-1.6-0.2l-7.8,6.1c-0.5,0.4-0.6,1.1-0.2,1.6   C76.6,24.5,77.4,24.6,77.9,24.2z\"><\/path>\t<path d=\"M73.1,27.9l1.6-1.3c0.5-0.4,0.6-1.1,0.2-1.6c-0.4-0.5-1.1-0.6-1.6-0.2l-1.6,1.3c-0.5,0.4-0.6,1.1-0.2,1.6   C71.9,28.2,72.6,28.3,73.1,27.9z\"><\/path>\t<path d=\"M56.4,74.4l9.1-3.8c0.6-0.2,0.9-0.9,0.6-1.5c-0.2-0.6-0.9-0.9-1.5-0.6l-9.1,3.8c-0.6,0.2-0.9,0.9-0.6,1.5   C55.2,74.3,55.8,74.6,56.4,74.4z\"><\/path>\t<path d=\"M50.9,76.7l1.9-0.8c0.6-0.2,0.9-0.9,0.6-1.5c-0.2-0.6-0.9-0.9-1.5-0.6L50,74.6c-0.6,0.2-0.9,0.9-0.6,1.5   C49.6,76.7,50.3,76.9,50.9,76.7z\"><\/path>\t<path d=\"M53.8,98.6L50,89.4c-0.2-0.6-0.9-0.9-1.5-0.6c-0.6,0.2-0.9,0.9-0.6,1.5l3.8,9.2c0.2,0.6,0.9,0.9,1.5,0.6   C53.8,99.9,54.1,99.2,53.8,98.6z\"><\/path>\t<path d=\"M48.4,85.7l-0.8-1.9c-0.2-0.6-0.9-0.9-1.5-0.6c-0.6,0.2-0.9,0.9-0.6,1.5l0.8,1.9c0.2,0.6,0.9,0.9,1.5,0.6   C48.4,87,48.7,86.3,48.4,85.7z\"><\/path>\t<path d=\"M15.6,39.2c0.6,0.2,1.3-0.1,1.5-0.7l3.6-9.2c0.2-0.6-0.1-1.3-0.7-1.5c-0.6-0.2-1.3,0.1-1.5,0.7L15,37.7   C14.8,38.3,15,38.9,15.6,39.2z\"><\/path>\t<path d=\"M13.4,44.8c0.6,0.2,1.3-0.1,1.5-0.7l0.8-1.9c0.2-0.6-0.1-1.3-0.7-1.5s-1.3,0.1-1.5,0.7l-0.8,1.9   C12.6,43.9,12.9,44.5,13.4,44.8z\"><\/path>\t<path d=\"M31.5,27.4l9.2,3.6c0.6,0.2,1.3-0.1,1.5-0.7c0.2-0.6-0.1-1.3-0.7-1.5l-9.2-3.6c-0.6-0.2-1.3,0.1-1.5,0.7   C30.6,26.5,30.9,27.2,31.5,27.4z\"><\/path>\t<path d=\"M25.9,25.2l1.9,0.8c0.6,0.2,1.3-0.1,1.5-0.7c0.2-0.6-0.1-1.3-0.7-1.5l-1.9-0.8c-0.6-0.2-1.3,0.1-1.5,0.7   C25,24.3,25.3,25,25.9,25.2z\"><\/path>\t<path d=\"M101.4,29.1c0.4,0.5,1.1,0.6,1.6,0.2c0.5-0.4,0.6-1.1,0.2-1.6l-6.1-7.8c-0.4-0.5-1.1-0.6-1.6-0.2c-0.5,0.4-0.6,1.1-0.2,1.6   L101.4,29.1z\"><\/path>\t<path d=\"M93,18.1c0.4,0.5,1.1,0.6,1.6,0.2c0.5-0.4,0.6-1.1,0.2-1.6l-1.3-1.6c-0.4-0.5-1.1-0.6-1.6-0.2c-0.5,0.4-0.6,1.1-0.2,1.6   L93,18.1z\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Brettspiele<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-mug-hot\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M127.1 146.5c1.3 7.7 8 13.5 16 13.5h16.5c9.8 0 17.6-8.5 16.3-18-3.8-28.2-16.4-54.2-36.6-74.7-14.4-14.7-23.6-33.3-26.4-53.5C111.8 5.9 105 0 96.8 0H80.4C70.6 0 63 8.5 64.1 18c3.9 31.9 18 61.3 40.6 84.4 12 12.2 19.7 27.5 22.4 44.1zm112 0c1.3 7.7 8 13.5 16 13.5h16.5c9.8 0 17.6-8.5 16.3-18-3.8-28.2-16.4-54.2-36.6-74.7-14.4-14.7-23.6-33.3-26.4-53.5C223.8 5.9 217 0 208.8 0h-16.4c-9.8 0-17.5 8.5-16.3 18 3.9 31.9 18 61.3 40.6 84.4 12 12.2 19.7 27.5 22.4 44.1zM400 192H32c-17.7 0-32 14.3-32 32v192c0 53 43 96 96 96h192c53 0 96-43 96-96h16c61.8 0 112-50.2 112-112s-50.2-112-112-112zm0 160h-16v-96h16c26.5 0 48 21.5 48 48s-21.5 48-48 48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kostenlosen Nachmittagstee<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4bcb5b elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b4bcb5b\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-coffee\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M192 384h192c53 0 96-43 96-96h32c70.6 0 128-57.4 128-128S582.6 32 512 32H120c-13.3 0-24 10.7-24 24v232c0 53 43 96 96 96zM512 96c35.3 0 64 28.7 64 64s-28.7 64-64 64h-32V96h32zm47.7 384H48.3c-47.6 0-61-64-36-64h583.3c25 0 11.8 64-35.9 64z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fr\u00fchst\u00fcck<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-wine-bottle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M507.31 72.57L439.43 4.69c-6.25-6.25-16.38-6.25-22.63 0l-22.63 22.63c-6.25 6.25-6.25 16.38 0 22.63l-76.67 76.67c-46.58-19.7-102.4-10.73-140.37 27.23L18.75 312.23c-24.99 24.99-24.99 65.52 0 90.51l90.51 90.51c24.99 24.99 65.52 24.99 90.51 0l158.39-158.39c37.96-37.96 46.93-93.79 27.23-140.37l76.67-76.67c6.25 6.25 16.38 6.25 22.63 0l22.63-22.63c6.24-6.24 6.24-16.37-.01-22.62zM179.22 423.29l-90.51-90.51 122.04-122.04 90.51 90.51-122.04 122.04z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Minibar an der Rezeption zum Kauf von Bieren und Weinen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3313c7 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"a3313c7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Bitte \u00fcberpr\u00fcfen Sie die angebotenen Dienstleistungen und lesen Sie unsere Richtlinien sorgf\u00e4ltig, bevor Sie Ihre Reservierung vornehmen.<\/span><\/p><p><span style=\"font-weight: 400;\">Reservieren Sie hier, um die besten Preise zu sichern**!\u00a0<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0b5ab0 elementor-align-left elementor-widget__width-initial button-style-seasona-yes elementor-invisible elementor-widget elementor-widget-button\" data-id=\"f0b5ab0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;shake&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/booking.hqbeds.com.br\/pousadanaturalia\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Online-Reservierung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd1c5f0 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"dd1c5f0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">*Die Reservierungsbest\u00e4tigung erfolgt nach Zahlung von 50 % des Gesamtbetrags, der Restbetrag wird in der Pousada bezahlt.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">**Die Preise k\u00f6nnen sich ohne vorherige Ank\u00fcndigung aufgrund von Marktschwankungen, W\u00e4hrungsschwankungen oder saisonalen Monaten \u00e4ndern. Der zum Zeitpunkt der Buchung vereinbarte Wert wird sich nicht \u00e4ndern, au\u00dfer im Falle einer m\u00f6glichen Terminverschiebung.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3191b25 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3191b25\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">WICHTIG ZU BEACHTEN VOR DER BUCHUNG\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a97012e elementor-position-left elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"a97012e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>.elementor-widget-image-box .elementor-image-box-content{width:100%}@media (min-width:768px){.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper,.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{display:flex}.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{text-align:end;flex-direction:row-reverse}.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper{text-align:start;flex-direction:row}.elementor-widget-image-box.elementor-position-top .elementor-image-box-img{margin:auto}.elementor-widget-image-box.elementor-vertical-align-top .elementor-image-box-wrapper{align-items:flex-start}.elementor-widget-image-box.elementor-vertical-align-middle .elementor-image-box-wrapper{align-items:center}.elementor-widget-image-box.elementor-vertical-align-bottom .elementor-image-box-wrapper{align-items:flex-end}}@media (max-width:767px){.elementor-widget-image-box .elementor-image-box-img{margin-left:auto!important;margin-right:auto!important;margin-bottom:15px}}.elementor-widget-image-box .elementor-image-box-img{display:inline-block}.elementor-widget-image-box .elementor-image-box-title a{color:inherit}.elementor-widget-image-box .elementor-image-box-wrapper{text-align:center}.elementor-widget-image-box .elementor-image-box-description{margin:0}<\/style><div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/naturaliapousada.com.br\/wp-content\/uploads\/elementor\/thumbs\/Reservas1-rn3dh0ja15hn6o9cqe4gsvqti5zcmgp7k9tt6o4e16.webp\" title=\"Reservas1\" alt=\"Reservas1\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\"><ul>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Struktur:<\/strong> Wir befinden uns etwa 100 Meter vom Strand entfernt, an einer rustikalen Kopfsteinpflastergasse mit einem relativ steilen Anstieg am Ende. Es gibt auch Treppen und Rampen innerhalb der Pousada. Daher empfehlen wir, die k\u00f6rperliche Verfassung jedes Gastes zu ber\u00fccksichtigen.<\/span><\/li><br>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Fernseher:<\/strong> Aus eigener Entscheidung und vor allem, um die Ruhe unserer G\u00e4ste zu bewahren, haben wir keine Fernseher in den Zimmern oder in den Einrichtungen der Pousada.<\/span><\/li><br>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Internet:<\/strong> Wir bieten die schnellsten Internetdienste an, die auf Ilha Grande verf\u00fcgbar sind, mit WLAN in den Zimmern und in unserem Gemeinschaftsbereich. Aufgrund der nat\u00fcrlichen Bedingungen auf einer Insel kann das Signal jedoch schwanken.<\/span><\/li><br>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Elektrizit\u00e4t:<\/strong> Vila do Abra\u00e3o verf\u00fcgt \u00fcber Elektrizit\u00e4t, aber der Dienst kann aufgrund von Wetter- und Problemen mit der Infrastruktur unterbrochen werden. Wir haben einen eigenen Generator, der von 18:00 bis 23:00 Uhr im Falle eines Stromausfalls betrieben wird.<\/span><\/li><\/ul>\n<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9ec2e9 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"d9ec2e9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Fr\u00fchst\u00fcck: <\/b><span style=\"font-weight: 400;\">Es wird von 8:00 bis 10:00 Uhr als kontinentales Buffet serviert, mit einer reichhaltigen Auswahl an frischen Fr\u00fcchten und S\u00e4ften, Joghurt und M\u00fcsli sowie Broten, Aufschnitt, Kuchen und R\u00fchrei. Wir bieten keine individuellen Extra-Zubereitungen an. Wenn Sie di\u00e4tetische Einschr\u00e4nkungen haben, informieren Sie uns bitte vorab bei der Buchung, und wir werden unser Bestes tun, um Ihre Bed\u00fcrfnisse zu erf\u00fcllen.<\/span><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ab120e4 e-flex e-con-boxed e-con e-parent\" data-id=\"ab120e4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4ebbd01 e-con-full e-flex e-con e-child\" data-id=\"4ebbd01\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9d8b6c elementor-position-right elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"e9d8b6c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/naturaliapousada.com.br\/wp-content\/uploads\/elementor\/thumbs\/Reservas2-rn3dh0j55q9t8mmss0xm2jjmqinizb8v8xlipfx8u8.webp\" title=\"Reservas2\" alt=\"Reservas2\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">RICHTLINIEN<\/h3><p class=\"elementor-image-box-description\"><h5><span style=\"font-weight: 400;\">Allgemeine Richtlinien<\/span><\/h5>\n<ul>\n  <li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Kinder:<\/strong> Wir akzeptieren Kinder erst ab 4 Jahren (sie gelten als regul\u00e4re zus\u00e4tzliche G\u00e4ste in Bezug auf den Tarif), und wir glauben, dass das ideale Alter ab 10 Jahren ist, aufgrund der topografischen Besonderheiten der Region und des Grundst\u00fccks (mit H\u00fcgeln, Rampen und Treppen).<\/span><\/li><br>\n  <li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Gruppen:<\/strong> Um die Qualit\u00e4t unserer Dienstleistungen sicherzustellen, akzeptieren wir Gruppen mit einer Begrenzung von 6 Personen, die maximal 3 Zimmer belegen.<\/span><\/li><br>\n  <li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Haustiere:<\/strong> Haustiere sind nicht erlaubt. Es gibt haustierfreundliche Pousadas in Vila do Abra\u00e3o. Bitte kontaktieren Sie uns f\u00fcr weitere Informationen.<\/span><\/li><br>\n  <li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Rauchen:<\/strong> Rauchen ist auf dem gesamten Gel\u00e4nde verboten, au\u00dfer auf dem privaten Balkon jedes Zimmers.<\/span><\/li>\n<\/ul>\n<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-818090e elementor-position-left elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"818090e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/naturaliapousada.com.br\/wp-content\/uploads\/elementor\/thumbs\/Reservas3-e1719876727365-rn3dh0j5rnnsuzry91w7pqmt3ndnsu295foyyyjv8k.webp\" title=\"Reservas3\" alt=\"Reservas3\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\"><h5><span style=\"font-weight: 400;\">\nZahlungsrichtlinie<\/span><\/h5>\n<ul><br>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><strong>Buchungsanzahlung:<\/strong> Mindestens 50 % des Gesamtbetrags der Reservierung m\u00fcssen \u00fcber Bank\u00fcberweisung, PayPal oder Kreditkarte mindestens 30 Tage vor dem Check-in Datum bezahlt werden. Der Restbetrag wird bei der Ankunft in der Pousada berechnet.<\/span><\/span><\/span><\/li><br>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><strong>W\u00e4hrung:<\/strong> Alle Geb\u00fchren werden in brasilianischen Reais (BRL), der lokalen W\u00e4hrung, erhoben. Ausnahmsweise und auf Anfrage k\u00f6nnen wir US-Dollar und Euro akzeptieren, wobei der Wechselkurs vom Management der Pousada gem\u00e4\u00df dem Tourismustarif festgelegt wird, einschlie\u00dflich einer zus\u00e4tzlichen Geb\u00fchr zur Deckung von Wechselkursschwankungen.<\/span><\/span><\/li>\n<\/ul>\n<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e242d2c elementor-position-right elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-vertical-align-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"e242d2c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/naturaliapousada.com.br\/wp-content\/uploads\/elementor\/thumbs\/Reservas4-rn3dh0j55q9t8mmss0xm2jjmqinizb8v8xlipfx8u8.webp\" title=\"Reservas4\" alt=\"Reservas4\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\"><h5><span style=\"font-weight: 400;\">\nStornierungsrichtlinie<\/span><\/h5><br>\n<ul>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><strong>F\u00fcr Standardreservierungen - Wenn die Reservierung storniert wird:<\/strong><\/span><\/li>\n<\/ul>\n<ol>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">30 Tage oder mehr vor dem Check-in: Stornierung kostenlos<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Zwischen 29 und 15 Tagen vor dem Check-in: 25 % des Gesamtbetrags der Reservierung<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Zwischen 14 und 7 Tagen vor dem Check-in: 50 % des Gesamtbetrags der Reservierung<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">6 Tage oder weniger vor dem Check-in oder im Falle eines Nichterscheinens: 100 % des Gesamtbetrags der Reservierung<\/span><\/li>\n<\/ol><br>\n<ul>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><strong>F\u00fcr Pakete und\/oder Gruppen von zwei oder mehr Zimmern - Wenn die Reservierung storniert wird:<\/strong><\/span><\/li>\n<\/ul>\n<ol>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">30 Tage oder mehr vor dem Check-in: freie Stornierung<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Zwischen 29 und 15 Tagen vor dem Check-in: 50 % des Gesamtbetrags der Reservierung<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">14 Tage oder weniger vor dem Check-in: 100 % des Gesamtbetrags der Reservierung<\/span><\/li>\n<\/ol>\n<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ac1dad elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6ac1dad\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h4><span style=\"font-weight: 400;\">Hinweis:<\/span><\/h4><ul><li style=\"list-style-type: none;\"><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Jegliche R\u00fcckerstattungen von bereits gezahlten Betr\u00e4gen werden gem\u00e4\u00df der oben genannten Richtlinie berechnet, mit einem Abzug von 10 % f\u00fcr Transaktionskosten.<br \/><br \/><\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Wir bieten keine Reservierungsumbuchungen oder Gutschriften an.<br \/><br \/><\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Stornierungskosten werden aufgrund von Wetterbedingungen nicht erlassen.<\/span><\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>RESERVIERUNGEN Sie k\u00f6nnen Ihre Reservierung direkt im Feld unten oder \u00fcber die E-Mail reservations@naturaliapousada.com.br\u00a0 Wir empfehlen mindestens drei volle Tage auf Ilha Grande, um die Str\u00e4nde, Wanderwege, Bootstouren und andere Aktivit\u00e4ten zu genie\u00dfen. Unser Tagespreis beinhaltet:\u00a0 WLAN Brettspiele Kostenlosen Nachmittagstee Fr\u00fchst\u00fcck Minibar an der Rezeption zum Kauf von Bieren und Weinen Bitte \u00fcberpr\u00fcfen Sie die [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9445,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"cybocfi_hide_featured_image":"yes","footnotes":""},"class_list":["post-12137","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reservierungen und Richtlinien | Pousada Naturalia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reservierungen und Richtlinien | Pousada Naturalia\" \/>\n<meta property=\"og:description\" content=\"RESERVIERUNGEN Sie k\u00f6nnen Ihre Reservierung direkt im Feld unten oder \u00fcber die E-Mail reservations@naturaliapousada.com.br\u00a0 Wir empfehlen mindestens drei volle Tage auf Ilha Grande, um die Str\u00e4nde, Wanderwege, Bootstouren und andere Aktivit\u00e4ten zu genie\u00dfen. Unser Tagespreis beinhaltet:\u00a0 WLAN Brettspiele Kostenlosen Nachmittagstee Fr\u00fchst\u00fcck Minibar an der Rezeption zum Kauf von Bieren und Weinen Bitte \u00fcberpr\u00fcfen Sie die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/\" \/>\n<meta property=\"og:site_name\" content=\"Pousada Naturalia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pousada.naturalia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-18T18:08:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/naturaliapousada.com.br\/wp-content\/uploads\/2024\/06\/capa-reservas-politicas-e1718759413675.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1429\" \/>\n\t<meta property=\"og:image:height\" content=\"535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/\",\"url\":\"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/\",\"name\":\"Reservierungen und Richtlinien | Pousada Naturalia\",\"isPartOf\":{\"@id\":\"https:\/\/naturaliapousada.com.br\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/naturaliapousada.com.br\/wp-content\/uploads\/2024\/06\/capa-reservas-politicas-e1718759413675.jpg\",\"datePublished\":\"2024-07-15T05:56:13+00:00\",\"dateModified\":\"2025-02-18T18:08:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/naturaliapousada.com.br\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reservierungen und Richtlinien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/naturaliapousada.com.br\/de\/#website\",\"url\":\"https:\/\/naturaliapousada.com.br\/de\/\",\"name\":\"Pousada Naturalia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/naturaliapousada.com.br\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/naturaliapousada.com.br\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/naturaliapousada.com.br\/de\/#organization\",\"name\":\"Pousada Naturalia\",\"url\":\"https:\/\/naturaliapousada.com.br\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/naturaliapousada.com.br\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/naturaliapousada.com.br\/wp-content\/uploads\/2020\/07\/02-logotipo-naturalia-preferencial-cobre-pousada.png\",\"contentUrl\":\"https:\/\/naturaliapousada.com.br\/wp-content\/uploads\/2020\/07\/02-logotipo-naturalia-preferencial-cobre-pousada.png\",\"width\":3564,\"height\":2967,\"caption\":\"Pousada Naturalia\"},\"image\":{\"@id\":\"https:\/\/naturaliapousada.com.br\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pousada.naturalia\",\"https:\/\/www.instagram.com\/pousada_naturalia\/\",\"https:\/\/www.youtube.com\/channel\/UCXutd46fOVdjuTPSxJFWQJw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reservierungen und Richtlinien | Pousada Naturalia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/","og_locale":"de_DE","og_type":"article","og_title":"Reservierungen und Richtlinien | Pousada Naturalia","og_description":"RESERVIERUNGEN Sie k\u00f6nnen Ihre Reservierung direkt im Feld unten oder \u00fcber die E-Mail reservations@naturaliapousada.com.br\u00a0 Wir empfehlen mindestens drei volle Tage auf Ilha Grande, um die Str\u00e4nde, Wanderwege, Bootstouren und andere Aktivit\u00e4ten zu genie\u00dfen. Unser Tagespreis beinhaltet:\u00a0 WLAN Brettspiele Kostenlosen Nachmittagstee Fr\u00fchst\u00fcck Minibar an der Rezeption zum Kauf von Bieren und Weinen Bitte \u00fcberpr\u00fcfen Sie die [&hellip;]","og_url":"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/","og_site_name":"Pousada Naturalia","article_publisher":"https:\/\/www.facebook.com\/pousada.naturalia","article_modified_time":"2025-02-18T18:08:40+00:00","og_image":[{"width":1429,"height":535,"url":"https:\/\/naturaliapousada.com.br\/wp-content\/uploads\/2024\/06\/capa-reservas-politicas-e1718759413675.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/","url":"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/","name":"Reservierungen und Richtlinien | Pousada Naturalia","isPartOf":{"@id":"https:\/\/naturaliapousada.com.br\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/#primaryimage"},"image":{"@id":"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/#primaryimage"},"thumbnailUrl":"https:\/\/naturaliapousada.com.br\/wp-content\/uploads\/2024\/06\/capa-reservas-politicas-e1718759413675.jpg","datePublished":"2024-07-15T05:56:13+00:00","dateModified":"2025-02-18T18:08:40+00:00","breadcrumb":{"@id":"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/naturaliapousada.com.br\/de\/reservierungen-und-richtlinien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/naturaliapousada.com.br\/de\/"},{"@type":"ListItem","position":2,"name":"Reservierungen und Richtlinien"}]},{"@type":"WebSite","@id":"https:\/\/naturaliapousada.com.br\/de\/#website","url":"https:\/\/naturaliapousada.com.br\/de\/","name":"Pousada Naturalia","description":"","publisher":{"@id":"https:\/\/naturaliapousada.com.br\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/naturaliapousada.com.br\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/naturaliapousada.com.br\/de\/#organization","name":"Pousada Naturalia","url":"https:\/\/naturaliapousada.com.br\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/naturaliapousada.com.br\/de\/#\/schema\/logo\/image\/","url":"https:\/\/naturaliapousada.com.br\/wp-content\/uploads\/2020\/07\/02-logotipo-naturalia-preferencial-cobre-pousada.png","contentUrl":"https:\/\/naturaliapousada.com.br\/wp-content\/uploads\/2020\/07\/02-logotipo-naturalia-preferencial-cobre-pousada.png","width":3564,"height":2967,"caption":"Pousada Naturalia"},"image":{"@id":"https:\/\/naturaliapousada.com.br\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pousada.naturalia","https:\/\/www.instagram.com\/pousada_naturalia\/","https:\/\/www.youtube.com\/channel\/UCXutd46fOVdjuTPSxJFWQJw"]}]}},"_links":{"self":[{"href":"https:\/\/naturaliapousada.com.br\/de\/wp-json\/wp\/v2\/pages\/12137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naturaliapousada.com.br\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/naturaliapousada.com.br\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/naturaliapousada.com.br\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/naturaliapousada.com.br\/de\/wp-json\/wp\/v2\/comments?post=12137"}],"version-history":[{"count":0,"href":"https:\/\/naturaliapousada.com.br\/de\/wp-json\/wp\/v2\/pages\/12137\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/naturaliapousada.com.br\/de\/wp-json\/wp\/v2\/media\/9445"}],"wp:attachment":[{"href":"https:\/\/naturaliapousada.com.br\/de\/wp-json\/wp\/v2\/media?parent=12137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}